{"id":8977,"date":"2023-07-31T18:33:22","date_gmt":"2023-07-31T21:33:22","guid":{"rendered":"http:\/\/blogdodanielgalvao.com.br\/site\/?p=8977"},"modified":"2023-07-31T18:33:22","modified_gmt":"2023-07-31T21:33:22","slug":"expo-macae-fortalecimento-do-agro-marca-edicao-2023","status":"publish","type":"post","link":"https:\/\/blogdodanielgalvao.com.br\/site\/expo-macae-fortalecimento-do-agro-marca-edicao-2023\/","title":{"rendered":"Expo Maca\u00e9: fortalecimento do agro marca edi\u00e7\u00e3o 2023"},"content":{"rendered":"<div>A Expo Maca\u00e9 2023 chegou ao fim neste domingo (30) deixando como saldo, al\u00e9m da extensa programa\u00e7\u00e3o de entretenimento \u00e0 popula\u00e7\u00e3o, o fortalecimento do setor agro com a realiza\u00e7\u00e3o de leil\u00f5es, concurso leiteiro, competi\u00e7\u00f5es equestres e espa\u00e7o para o produtor rural. O evento foi realizado de 26 a 30 de julho, em comemora\u00e7\u00e3o aos 210 anos da cidade, no Parque de Exposi\u00e7\u00f5es Latiff Mussi.<\/div>\n<div>O Secret\u00e1rio de Agroeconomia, Dudu Jardim, avalia que os bons resultados obtidos na Expo s\u00e3o frutos da proximidade do governo municipal e do olhar atento \u00e0s demandas e necessidades do setor. &#8220;Vimos os produtores de diferentes \u00e1reas se sentindo muito prestigiados. O respeito com que a administra\u00e7\u00e3o p\u00fablica vem tratando os atores que atuam nessa atividade econ\u00f4mica \u00e9 um impulsionador para o alcance de n\u00fameros expressivos com os obtidos na Exposi\u00e7\u00e3o Agropecu\u00e1ria e consolidam o potencial gigantesco de Maca\u00e9 no agroneg\u00f3cio&#8221;, destacou.<\/p>\n<p>O leil\u00e3o de criadores contou com a comercializa\u00e7\u00e3o com liquidez total de 660 animais e o envolvimento de cerca de 80 pecuaristas de Maca\u00e9 e regi\u00e3o. &#8220;O tatersal do leil\u00e3o de gado foi reformado, o espa\u00e7o climatizado, al\u00e9m da coloca\u00e7\u00e3o de piso frio, isso demonstra o carinho da Prefeitura em aprimorar cada vez mais a infraestrutura do Parque. Essa retomada da comercializa\u00e7\u00e3o do gado de corte \u00e9 muito importante para Maca\u00e9 e aquece todo um setor. Os participantes deste leil\u00e3o j\u00e1 est\u00e3o marcando um novo para daqui a 90 dias, com o envolvimento 1000 animais&#8221;, ressaltou Dudu Jardim.<\/p>\n<p>O Secret\u00e1rio aponta ainda a participa\u00e7\u00e3o do governo estadual no evento. &#8220;\u00d3rg\u00e3os como a Emater, Pesagro e Defesa Sanit\u00e1ria se fizeram presentes refor\u00e7ando a import\u00e2ncia da nossa Expo. O prest\u00edgio do evento tamb\u00e9m pode ser medido com o incremento da participa\u00e7\u00e3o de empresas do ramo do agroneg\u00f3cio que levaram maquin\u00e1rios, implementos agr\u00edcolas, vag\u00f5es forrageiros, entre outros&#8221;.<\/p>\n<p>Os produtores rurais tamb\u00e9m tiveram espa\u00e7o na festa. No Galp\u00e3o da Agricultura Familiar eles puderam comercializar produtos como verduras, mel e itens artesanais como p\u00e3o sem gl\u00faten e massas \u00e0 base de aipim, beneficiando toda uma cadeia que atua na produ\u00e7\u00e3o e com\u00e9rcio da economia solid\u00e1ria.<\/p>\n<p>Outro ponto alto da programa\u00e7\u00e3o foram as competi\u00e7\u00f5es que atra\u00edram os amantes dos esportes equestres. &#8220;No la\u00e7o campista contamos com a participa\u00e7\u00e3o de mais de 150 lan\u00e7adores; tivemos ainda o julgamento das ra\u00e7as Zebu Nelore e Tabapu\u00e3, com ju\u00edzes renomados da Associa\u00e7\u00e3o Brasileira dos Criadores de Zebu (ABCZ). J\u00e1 no Campeonato de Marcha da Ra\u00e7a Campolina, foram expostos 100 animais de criadores da mais alta performance&#8217;, detalha o Secret\u00e1rio de Agroeconomia.<\/p>\n<p>&#8220;A Expo fez com que o mundo do agroneg\u00f3cio se fizesse presente em Maca\u00e9. Pessoas do Esp\u00edrito Santo, S\u00e3o Paulo, Rio de Janeiro e outros locais foram atra\u00eddas pela qualidade do nosso evento e pela notoriedade que o munic\u00edpio vem ganhando&#8221;, avalia Dudu.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Expo Maca\u00e9 2023 chegou ao fim neste domingo (30) deixando como saldo, al\u00e9m da extensa programa\u00e7\u00e3o de entretenimento \u00e0 popula\u00e7\u00e3o, o fortalecimento do setor agro com a realiza\u00e7\u00e3o de leil\u00f5es, concurso leiteiro, competi\u00e7\u00f5es equestres e espa\u00e7o para o produtor rural. O evento foi realizado de 26 a 30 de julho, em comemora\u00e7\u00e3o aos 210 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-8977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-macae"],"_links":{"self":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts\/8977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/comments?post=8977"}],"version-history":[{"count":1,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts\/8977\/revisions"}],"predecessor-version":[{"id":8979,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts\/8977\/revisions\/8979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/media\/8978"}],"wp:attachment":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/media?parent=8977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/categories?post=8977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/tags?post=8977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}