{"id":19677,"date":"2025-06-13T17:00:24","date_gmt":"2025-06-13T20:00:24","guid":{"rendered":"https:\/\/blogdodanielgalvao.com.br\/site\/?p=19677"},"modified":"2025-06-13T17:00:24","modified_gmt":"2025-06-13T20:00:24","slug":"pai-e-preso-em-campos-apos-ameacas-de-morte-e-agressao-a-filha","status":"publish","type":"post","link":"https:\/\/blogdodanielgalvao.com.br\/site\/pai-e-preso-em-campos-apos-ameacas-de-morte-e-agressao-a-filha\/","title":{"rendered":"Pai \u00e9 preso em Campos ap\u00f3s amea\u00e7as de morte e agress\u00e3o \u00e0 filha"},"content":{"rendered":"<p>Um homem foi preso pela Delegacia Especializada de Atendimento \u00e0 Mulher (DEAM) na \u00faltima quinta-feira (12) em Campos por ter amea\u00e7ado a pr\u00f3pria filha. O acusado tem 35 anos e segundo informa\u00e7\u00f5es, teria amea\u00e7ado tirar a vida da adolescente de 16 anos.<\/p>\n<p>De acordo com o relato da jovem, ela tamb\u00e9m foi agredida fisicamente pelo pai. O agressor a amea\u00e7ou de morte e a proibiu de sair de casa ap\u00f3s descobrir que ela estava namorando. Ainda segundo informa\u00e7\u00f5es, o pai tamb\u00e9m teria enviado mensagens com amea\u00e7as, afirmando que iria acabar com a vida da filha e do namorado dela.<\/p>\n<p>Com base nas amea\u00e7as e agress\u00f5es, a filha procurou a delegacia para relatar o caso e pedir a medida protetiva.<\/p>\n<p>A pol\u00edcia montou a opera\u00e7\u00e3o e conseguiu localizar o pai da v\u00edtima que foi preso em oferecer resist\u00eancia. Ele foi autuado em flagrante pelo crime de amea\u00e7a al\u00e9m de agora ser investigado por les\u00e3o corporal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso pela Delegacia Especializada de Atendimento \u00e0 Mulher (DEAM) na \u00faltima quinta-feira (12) em Campos por ter amea\u00e7ado a pr\u00f3pria filha. O acusado tem 35 anos e segundo informa\u00e7\u00f5es, teria amea\u00e7ado tirar a vida da adolescente de 16 anos. De acordo com o relato da jovem, ela tamb\u00e9m foi agredida fisicamente pelo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19678,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1899],"tags":[494],"class_list":["post-19677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-policia"],"_links":{"self":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts\/19677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/comments?post=19677"}],"version-history":[{"count":1,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts\/19677\/revisions"}],"predecessor-version":[{"id":19679,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/posts\/19677\/revisions\/19679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/media\/19678"}],"wp:attachment":[{"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/media?parent=19677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/categories?post=19677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdodanielgalvao.com.br\/site\/wp-json\/wp\/v2\/tags?post=19677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}